{"id":4174,"date":"2023-04-12T19:40:18","date_gmt":"2023-04-12T17:40:18","guid":{"rendered":"https:\/\/familiengemeinde.ch\/index.php\/cookie-richtlinie-eu\/"},"modified":"2023-04-12T19:40:20","modified_gmt":"2023-04-12T17:40:20","slug":"cookie-richtlinie-eu","status":"publish","type":"page","link":"https:\/\/familiengemeinde.ch\/index.php\/cookie-richtlinie-eu\/","title":{"rendered":"Cookie-Richtlinie (EU)"},"content":{"rendered":"\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Diese Cookie-Richtlinie wurde zuletzt am 6. Dezember 2023 aktualisiert und gilt f\u00fcr B\u00fcrger und Einwohner mit st\u00e4ndigem Wohnsitz im Europ\u00e4ischen Wirtschaftsraum und der Schweiz.<\/i><br><\/p><h2>1. Einf\u00fchrung<\/h2><p>Unsere Website, <a href=\"https:\/\/familiengemeinde.ch\">https:\/\/familiengemeinde.ch<\/a> (im folgenden: \"Die Website\") verwendet Cookies und \u00e4hnliche Technologien (der Einfachheit halber werden all diese unter \"Cookies\" zusammengefasst). Cookies werden au\u00dferdem von uns beauftragten Drittparteien platziert. In dem unten stehendem Dokument informieren wir dich \u00fcber die Verwendung von Cookies auf unserer Website.<\/p><h2>2. Was sind Cookies?<\/h2><p>Ein Cookie ist eine einfache kleine Datei, die gemeinsam mit den Seiten einer Internetadresse versendet und vom Webbrowser auf dem PC oder einem anderen Ger\u00e4t gespeichert werden kann. Die darin gespeicherten Informationen k\u00f6nnen w\u00e4hrend folgender Besuche zu unseren oder den Servern relevanter Drittanbieter gesendet werden.<\/p><h2>3. Was sind Skripte?<\/h2><p>Ein Script ist ein St\u00fcck Programmcode, das benutzt wird, um unserer Website Funktionalit\u00e4t und Interaktivit\u00e4t zu erm\u00f6glichen. Dieser Code wird auf unseren Servern oder auf deinem Ger\u00e4t ausgef\u00fchrt.<\/p><h2>4. Was ist ein Web Beacon?<\/h2><p>Ein Web-Beacon (auch Pixel-Tag genannt), ist ein kleines unsichtbares Textfragment oder Bild auf einer Website, das benutzt wird, um den Verkehr auf der Website zu \u00fcberwachen. Um dies zu erm\u00f6glichen werden diverse Daten von dir mittels Web-Beacons gespeichert.<\/p><h2>5. Cookies<\/h2><p class=\"cmplz-subtitle\">5.1 Technische oder funktionelle Cookies<\/p><p>Einige Cookies stellen sicher, dass bestimmte Teile der Website ordnungsgem\u00e4\u00df funktionieren und deine Benutzereinstellungen weiterhin in Erinnerung bleiben. Durch das Setzen funktionaler Cookies erleichtern wir dir den Besuch unserer Website. Auf diese Weise musst du beim Besuch unserer Website nicht wiederholt dieselben Informationen eingeben, so bleiben Artikel beispielsweise in deinem Warenkorb, bis du bezahlst. Wir k\u00f6nnen diese Cookies ohne deine Einwilligung platzieren.<\/p><p class=\"cmplz-subtitle\">5.2 Analytische Cookies<\/p><p>Wir verwenden analytische Cookies, um das Website-Erlebnis f\u00fcr unsere Nutzer zu optimieren. Mit diesen analytischen Cookies erhalten wir Einblicke in die Nutzung unserer Website.&nbsp;Wir bitten um deine Erlaubnis, analytische Cookies zu setzen.<\/p><p class=\"cmplz-subtitle\">5.3 Marketing- \/ Tracking-Cookies<\/p><p>Marketing- \/ Tracking-Cookies sind Cookies oder eine andere Form der lokalen Speicherung, die zur Erstellung von Benutzerprofilen verwendet werden, um Werbung anzuzeigen oder den Benutzer auf dieser Website oder \u00fcber mehrere Websites hinweg f\u00fcr \u00e4hnliche Marketingzwecke zu verfolgen.<\/p><h2>6. Platzierte Cookies<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>PayPal<\/h3>\n\t\t<p>Funktional<\/p>\n\t\t<label for=\"cmplz_service_paypal\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service paypal<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_paypal\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"paypal\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden PayPal f\u00fcr Zahlungsabwicklung. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/paypal\/\">Weitere Informationen zu PayPal<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.paypal.com\/legalhub\/privacy-full\">PayPal Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funktional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/paypal\/__paypal_storage__\/\">__paypal_storage__<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">best\u00e4ndig<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Benutzer-Details<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/paypal\/nsid\/\">nsid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Beuge Betrug vor<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/paypal\/enforce_policy\/\">enforce_policy<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Jahr<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere pers\u00f6nliche Vorlieben<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/paypal\/tsrce\/\">tsrce<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">3 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/paypal\/auto-draft-3\/\">ts_c<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">3 Jahre<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Beuge Betrug vor<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Elementor<\/h3>\n\t\t<p>Statistik (anonym)<\/p>\n\t\t<label for=\"cmplz_service_elementor\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service elementor<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_elementor\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"elementor\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden Elementor f\u00fcr Inhaltserstellung. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/elementor\/\">Weitere Informationen zu Elementor<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Diese Daten werden nicht an Dritte weitergegeben.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistik (anonym)<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/elementor\/elementor\/\">elementor<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">best\u00e4ndig<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere durchgef\u00fchrte Aktionen der Benutzer auf der Website<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden WordPress f\u00fcr Website-Entwicklung. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/wordpress\/\">Weitere Informationen zu WordPress<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Diese Daten werden nicht an Dritte weitergegeben.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_test_cookie\/\">wordpress_test_cookie<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Read if cookies can be placed<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings-time\/\">wp-settings-time-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 year<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Store user preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wp-settings\/\">wp-settings-*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Store user preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/wordpress\/wordpress_logged_in_\/\">wordpress_logged_in_*<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Store logged in users<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Analytics<\/h3>\n\t\t<p>Statistik<\/p>\n\t\t<label for=\"cmplz_service_google-analytics\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-analytics<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-analytics\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-analytics\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden Google Analytics f\u00fcr Website-Statistik. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-analytics\/\">Weitere Informationen zu Google Analytics<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google Analytics Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Statistik<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_ga\/\">_ga<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">2 Jahre<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Z\u00e4hlt und verfolgt Seitenaufrufe<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-analytics\/_gid\/\">_gid<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">1 Tag<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Z\u00e4hlt und verfolgt Seitenaufrufe<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Marketing\/Tracking<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden Google Fonts f\u00fcr Anzeige von Webfonts. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-fonts\/\">Weitere Informationen zu Google Fonts<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google Fonts Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing\/Tracking<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-fonts\/tcb_google_fonts\/\">Google Fonts API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">keins<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Fordere die Benutzer-IP-Adresse an<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google reCAPTCHA<\/h3>\n\t\t<p>Marketing\/Tracking<\/p>\n\t\t<label for=\"cmplz_service_google-recaptcha\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-recaptcha<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-recaptcha\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-recaptcha\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden Google reCAPTCHA f\u00fcr Spam-Vorbeugung. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-recaptcha\/\">Weitere Informationen zu Google reCAPTCHA<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google reCAPTCHA Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing\/Tracking<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcc\/\">rc::c<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Anfragen von Bots lesen und filtern<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rcb\/\">rc::b<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Anfragen von Bots lesen und filtern<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-recaptcha\/rca\/\">rc::a<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">best\u00e4ndig<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Anfragen von Bots lesen und filtern<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>Marketing\/Tracking<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-maps\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden Google Maps f\u00fcr Kartenanzeige. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/google-maps\/\">Weitere Informationen zu Google Maps<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google Maps Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing\/Tracking<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/google-maps\/google-maps-api\/\">Google Maps API<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">keins<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Fordere die Benutzer-IP-Adresse an<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>YouTube<\/h3>\n\t\t<p>Marketing\/Tracking, Funktional<\/p>\n\t\t<label for=\"cmplz_service_youtube\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service youtube<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_youtube\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"youtube\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p>Wir verwenden YouTube f\u00fcr Video-Display. <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/service\/youtube\/\">Weitere Informationen zu YouTube<\/a><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>F\u00fcr weitere Informationen, bitte die <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">YouTube Datenschutzerkl\u00e4rung<\/a> lesen.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing\/Tracking<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/gps\/\">GPS<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speichere Standortdaten<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/ysc\/\">YSC<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">Sitzung<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Interaktion speichern und verfolgen<\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/pref\/\">PREF<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">8 Monate<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Speicher die Benutzervorlieben<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Funktional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\"><a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/cookiedatabase.org\/cookie\/youtube\/visitor_info1_live\/\">VISITOR_INFO1_LIVE<\/a><\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">6 Monate<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\">Sch\u00e4tzungen der Bandbreite liefern<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Sonstiges<\/h3>\n\t\t<p>Gegenstand der Untersuchung<\/p>\n\t\t<label for=\"cmplz_service_sonstiges\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service sonstiges<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_sonstiges\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"sonstiges\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Verwendung<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Weitergabe von Daten<\/h4>\n\t\t<p>Die Weitergabe von Daten wird noch untersucht<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Gegenstand der Untersuchung<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">e_kit-elements-defaults<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">OceanCustomizePreviewUrl<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cs-aHR0cHM6Ly9mYW1pbGllbmdlbWVpbmRlLmNoLy8=-cs-max-data<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_grecaptcha<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\">365 Tage<\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wpEmojiSettingsSupports<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wp_lang<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">9eir9yqi<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">lr3klirz<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">4zd7zf26<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">9cpivo4w<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">n7z6obd0<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">y2day0pq<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">aw5i5jjv<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">p1y6phk6<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">z2pksb96<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">343qoc0n<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">fbew6gih<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">oef4wcoo<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">tz6pytay<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">_gat<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">4jfx7qs6<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">creun1hk<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">lxush7e5<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">w7tiyum8<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">6aq1vq1n<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">qsc7eyl0<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">rey2rwpr<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">u9fjsafj<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">7xdjpcu8<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">9vq2fpa2<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">mntfrisg<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">t5iiycm7<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">6fi37cbt<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">z05dqpa2<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">ai_promotion_introduction_editor_session_key<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">2sc7awrv<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">wvob91kx<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">mp_150605b3b9f979922f2ac5a52e2dcfe9_mixpanel<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">mp_gen_new_tab_id_mixpanel_150605b3b9f979922f2ac5a52e2dcfe9<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">mp_tab_id_mixpanel_150605b3b9f979922f2ac5a52e2dcfe9<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Name<\/h5>\n<\/div>\n<div class=\"name\">hfeSelectedItemId<\/div>\n<div class=\"retention-header\">\n\t<h5>Ablaufdatum<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Funktion<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Einwilligung<\/h2><p>Wenn du unsere Website das erste Mal besuchst, zeigen wir dir ein Pop-Up mit einer Erkl\u00e4rung \u00fcber Cookies. Sobald du auf \u201eEinstellungen speichern\u201c klickst, gibst du uns deine Einwilligung alle von dir gew\u00e4hlten Kategorien von Cookies und Plugins wie in dieser Cookie-Erkl\u00e4rung beschrieben zu verwenden. Du kannst die Verwendung von Cookies \u00fcber deinen Browser deaktivieren, aber bitte beachte, dass unsere Website dann unter Umst\u00e4nden nicht richtig funktioniert.<\/p><p class=\"cmplz-subtitle\">7.1 Verwalte deine Einwilligungseinstellungen<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Du hast die Cookie-Richtlinie ohne Javascript-Unterst\u00fctzung geladen.&nbsp;Unter AMP kannst du den Button zum Zustimmen der Einwilligung unten auf der Seite verwenden.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Aktivierung\/Deaktivierung und L\u00f6schen von Cookies<\/h2><p>Du kannst deinen Internetbrowser verwenden um automatisch oder manuell Cookies zu l\u00f6schen. Du kannst au\u00dferdem spezifizieren ob spezielle Cookies nicht platziert werden sollen. Eine andere M\u00f6glichkeit ist es deinen  Internetbrowser derart einzurichten, dass du jedes Mal benachrichtigt wirst, wenn ein Cookie platziert wird. F\u00fcr weitere Information \u00fcber diese M\u00f6glichkeiten beachte die Anweisungen in der Hilfesektion deines Browsers.<\/p><p>Bitte nimm zur Kenntnis, dass unsere Website m\u00f6glicherweise nicht richtig funktioniert, wenn alle Cookies deaktiviert sind. Wenn du die Cookies in deinem Browser l\u00f6scht, werden diese neu platziert, wenn du unsere Website erneut besuchst.<\/p><h2>9. Deine Rechte in Bezug auf personenbezogene Daten<\/h2><p>Du hast folgende Rechte in Bezug auf deine personenbezogenen Daten:<\/p><ul>\n                    <li>Du hast das Recht zu erfahren, warum deine personenbezogenen Daten ben\u00f6tigt werden, was damit passiert und wie lange sie aufbewahrt werden.<\/li>\n                    <li>Auskunftsrecht: Du hast das Recht deine uns bekannten pers\u00f6nliche Daten einzusehen.\n\t<\/li>\n                    <li>Recht auf Berichtigung: Du hast das Recht wann immer du w\u00fcnscht, deine personenbezogenen Daten zu erg\u00e4nzen, zu korrigieren sowie gel\u00f6scht oder blockiert zu bekommen.<\/li>\n                    <li>Wenn du uns deine Einwilligung zur Verarbeitung deiner Daten erteilst, hast du das Recht diese Einwilligung zu widerrufen und deine personenbezogenen Daten l\u00f6schen zu lassen.<\/li>\n                    <li>Recht auf Daten\u00fcbertragbarkeit: Du hast das Recht, alle deine personenbezogenen Daten von dem f\u00fcr die Verarbeitung Verantwortlichen anzufordern und sie vollst\u00e4ndig an einen anderen f\u00fcr die Verarbeitung Verantwortlichen zu \u00fcbermitteln.<\/li>\n                    <li>Widerspruchsrecht: Du kannst der Verarbeitung deiner Daten widersprechen. Wir entsprechen dem, es sei denn es gibt berechtigte Gr\u00fcnde f\u00fcr die Verarbeitung.<\/li>\n                <\/ul><p>Um diese Rechte auszu\u00fcben kontaktiere uns bitte. Bitte beziehe dich auf die Kontaktdaten am Ende dieser Cookie-Erkl\u00e4rung. Wenn du eine Beschwerde dar\u00fcber hast, wie wir deine Daten behandeln, w\u00fcrden wir diese gerne h\u00f6ren, aber du hast auch das Recht diese an die Aufsichtsbeh\u00f6rde (Datenschutzbeh\u00f6rde) zu richten.<\/p><h2>10. Kontaktdaten<\/h2><p>F\u00fcr Fragen und\/oder Kommentare \u00fcber unsere Cookie-Richtlinien und diese Aussage kontaktiere uns bitte mittels der folgenden Kontaktdaten:<\/p><p><span class=\"cmplz-contact-organisation\">Familiengemeinde Langenthal<\/span><br>\n                      <span class=\"cmplz-contact-address\">Bleienbachstrasse 8, 4900 Langenthal<\/span><br>\n                      <span class=\"cmplz-contact-country\">Schweiz<\/span><br>\n                      <span class=\"cmplz-contact-domain\">Website: <a href=\"https:\/\/familiengemeinde.ch\">https:\/\/familiengemeinde.ch<\/a><\/span><br>\n                      <span class=\"cmplz-contact-email\">E-Mail: <span class=\"cmplz-obfuscate\">i&#110;&#102;&#111;@<span class=\"cmplz-fmail-domain\">&#101;x&#046;c&#111;&#109;<\/span>&#102;&#097;m&#105;l&#105;&#101;n&#103;e&#109;&#101;i&#110;&#100;&#101;.&#099;&#104;<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\"><\/span><\/p><p>Diese Cookie-Richtlinie wurde mit <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> am 12. April 2023 synchronisiert.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4174","page","type-page","status-publish","hentry","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cookie-Richtlinie (EU) - Familiengemeinde<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/familiengemeinde.ch\/index.php\/cookie-richtlinie-eu\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cookie-Richtlinie (EU) - Familiengemeinde\" \/>\n<meta property=\"og:url\" content=\"https:\/\/familiengemeinde.ch\/index.php\/cookie-richtlinie-eu\/\" \/>\n<meta property=\"og:site_name\" content=\"Familiengemeinde\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-12T17:40:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/familiengemeinde.ch\\\/index.php\\\/cookie-richtlinie-eu\\\/\",\"url\":\"https:\\\/\\\/familiengemeinde.ch\\\/index.php\\\/cookie-richtlinie-eu\\\/\",\"name\":\"Cookie-Richtlinie (EU) - Familiengemeinde\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/familiengemeinde.ch\\\/#website\"},\"datePublished\":\"2023-04-12T17:40:18+00:00\",\"dateModified\":\"2023-04-12T17:40:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/familiengemeinde.ch\\\/index.php\\\/cookie-richtlinie-eu\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/familiengemeinde.ch\\\/index.php\\\/cookie-richtlinie-eu\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/familiengemeinde.ch\\\/index.php\\\/cookie-richtlinie-eu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/familiengemeinde.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cookie-Richtlinie (EU)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/familiengemeinde.ch\\\/#website\",\"url\":\"https:\\\/\\\/familiengemeinde.ch\\\/\",\"name\":\"Familiengemeinde Langenthal\",\"description\":\"Freikirche in Langenthal\",\"publisher\":{\"@id\":\"https:\\\/\\\/familiengemeinde.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/familiengemeinde.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/familiengemeinde.ch\\\/#organization\",\"name\":\"Familiengemeinde Langenthal\",\"url\":\"https:\\\/\\\/familiengemeinde.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/familiengemeinde.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/familiengemeinde.ch\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/familiengemeinde_logo-2.png\",\"contentUrl\":\"https:\\\/\\\/familiengemeinde.ch\\\/wp-content\\\/uploads\\\/2015\\\/10\\\/familiengemeinde_logo-2.png\",\"width\":1868,\"height\":384,\"caption\":\"Familiengemeinde Langenthal\"},\"image\":{\"@id\":\"https:\\\/\\\/familiengemeinde.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cookie-Richtlinie (EU) - Familiengemeinde","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/familiengemeinde.ch\/index.php\/cookie-richtlinie-eu\/","og_locale":"de_DE","og_type":"article","og_title":"Cookie-Richtlinie (EU) - Familiengemeinde","og_url":"https:\/\/familiengemeinde.ch\/index.php\/cookie-richtlinie-eu\/","og_site_name":"Familiengemeinde","article_modified_time":"2023-04-12T17:40:20+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/familiengemeinde.ch\/index.php\/cookie-richtlinie-eu\/","url":"https:\/\/familiengemeinde.ch\/index.php\/cookie-richtlinie-eu\/","name":"Cookie-Richtlinie (EU) - Familiengemeinde","isPartOf":{"@id":"https:\/\/familiengemeinde.ch\/#website"},"datePublished":"2023-04-12T17:40:18+00:00","dateModified":"2023-04-12T17:40:20+00:00","breadcrumb":{"@id":"https:\/\/familiengemeinde.ch\/index.php\/cookie-richtlinie-eu\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/familiengemeinde.ch\/index.php\/cookie-richtlinie-eu\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/familiengemeinde.ch\/index.php\/cookie-richtlinie-eu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/familiengemeinde.ch\/"},{"@type":"ListItem","position":2,"name":"Cookie-Richtlinie (EU)"}]},{"@type":"WebSite","@id":"https:\/\/familiengemeinde.ch\/#website","url":"https:\/\/familiengemeinde.ch\/","name":"Familiengemeinde Langenthal","description":"Freikirche in Langenthal","publisher":{"@id":"https:\/\/familiengemeinde.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/familiengemeinde.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/familiengemeinde.ch\/#organization","name":"Familiengemeinde Langenthal","url":"https:\/\/familiengemeinde.ch\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/familiengemeinde.ch\/#\/schema\/logo\/image\/","url":"https:\/\/familiengemeinde.ch\/wp-content\/uploads\/2015\/10\/familiengemeinde_logo-2.png","contentUrl":"https:\/\/familiengemeinde.ch\/wp-content\/uploads\/2015\/10\/familiengemeinde_logo-2.png","width":1868,"height":384,"caption":"Familiengemeinde Langenthal"},"image":{"@id":"https:\/\/familiengemeinde.ch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/familiengemeinde.ch\/index.php\/wp-json\/wp\/v2\/pages\/4174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/familiengemeinde.ch\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/familiengemeinde.ch\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/familiengemeinde.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/familiengemeinde.ch\/index.php\/wp-json\/wp\/v2\/comments?post=4174"}],"version-history":[{"count":1,"href":"https:\/\/familiengemeinde.ch\/index.php\/wp-json\/wp\/v2\/pages\/4174\/revisions"}],"predecessor-version":[{"id":4176,"href":"https:\/\/familiengemeinde.ch\/index.php\/wp-json\/wp\/v2\/pages\/4174\/revisions\/4176"}],"wp:attachment":[{"href":"https:\/\/familiengemeinde.ch\/index.php\/wp-json\/wp\/v2\/media?parent=4174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}